{"id":7211,"date":"2016-12-06T10:13:55","date_gmt":"2016-12-06T09:13:55","guid":{"rendered":"https:\/\/lesgentilspariziens.com\/portfolio\/blue-on-white-jean-marc-fondimare\/"},"modified":"2020-06-01T11:12:06","modified_gmt":"2020-06-01T09:12:06","slug":"blue-on-white-jean-marc-fondimare","status":"publish","type":"portfolio","link":"https:\/\/lesgentilspariziens.com\/en\/portfolio\/blue-on-white-jean-marc-fondimare\/","title":{"rendered":"blue on white (jean marc fondimare)"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE-.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"526\" src=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE--1024x526.jpg\" alt=\"\" data-id=\"7055\" data-full-url=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE-.jpg\" data-link=\"https:\/\/lesgentilspariziens.com\/portfolio\/blue-on-white-jean-marc-fondimare\/blue\/\" class=\"wp-image-7055\" srcset=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE--1024x526.jpg 1024w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE--300x154.jpg 300w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE--768x395.jpg 768w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE--1536x790.jpg 1536w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/BLUE-.jpg 1700w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"featured_media":0,"template":"","class_list":["post-7211","portfolio","type-portfolio","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/portfolio\/7211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:attachment":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/media?parent=7211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}