{"id":7244,"date":"2016-08-23T09:49:00","date_gmt":"2016-08-23T07:49:00","guid":{"rendered":"https:\/\/lesgentilspariziens.com\/portfolio\/sanctuaire-ludovic-winterstan\/"},"modified":"2016-08-23T09:49:00","modified_gmt":"2016-08-23T07:49:00","slug":"sanctuaire-ludovic-winterstan","status":"publish","type":"portfolio","link":"https:\/\/lesgentilspariziens.com\/en\/portfolio\/sanctuaire-ludovic-winterstan\/","title":{"rendered":"sanctuaire (ludovic winterstan)"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"526\" src=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire-1024x526.jpg\" alt=\"\" data-id=\"6532\" data-full-url=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire.jpg\" data-link=\"https:\/\/lesgentilspariziens.com\/portfolio\/sanctuaire-ludovic-winterstan\/sanctuaire\/\" class=\"wp-image-6532\" srcset=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire-1024x526.jpg 1024w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire-300x154.jpg 300w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire-768x395.jpg 768w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire-1536x790.jpg 1536w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/sanctuaire.jpg 1700w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"featured_media":0,"template":"","class_list":["post-7244","portfolio","type-portfolio","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/portfolio\/7244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:attachment":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/media?parent=7244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}