{"id":7248,"date":"2016-07-11T10:04:55","date_gmt":"2016-07-11T08:04:55","guid":{"rendered":"https:\/\/lesgentilspariziens.com\/portfolio\/freshness-claes-iversen\/"},"modified":"2016-07-11T10:04:55","modified_gmt":"2016-07-11T08:04:55","slug":"freshness-claes-iversen","status":"publish","type":"portfolio","link":"https:\/\/lesgentilspariziens.com\/en\/portfolio\/freshness-claes-iversen\/","title":{"rendered":"freshness (claes iversen)"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"526\" src=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness-1024x526.jpg\" alt=\"\" data-id=\"6536\" data-full-url=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness.jpg\" data-link=\"https:\/\/lesgentilspariziens.com\/portfolio\/freshness-claes-iversen\/freshness\/\" class=\"wp-image-6536\" srcset=\"https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness-1024x526.jpg 1024w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness-300x154.jpg 300w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness-768x395.jpg 768w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness-1536x790.jpg 1536w, https:\/\/lesgentilspariziens.com\/wp-content\/uploads\/2020\/05\/freshness.jpg 1700w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"featured_media":0,"template":"","class_list":["post-7248","portfolio","type-portfolio","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/portfolio\/7248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:attachment":[{"href":"https:\/\/lesgentilspariziens.com\/en\/wp-json\/wp\/v2\/media?parent=7248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}